{"id":2083,"date":"2017-11-29T14:42:37","date_gmt":"2017-11-29T13:42:37","guid":{"rendered":"http:\/\/pugsada.org\/wordpress\/?p=2083"},"modified":"2018-06-21T11:14:45","modified_gmt":"2018-06-21T10:14:45","slug":"lutte-contre-grossesses-precocesnon-desirees-milieu-scolaire","status":"publish","type":"post","link":"https:\/\/pugsada.org\/wordpress\/lutte-contre-grossesses-precocesnon-desirees-milieu-scolaire\/","title":{"rendered":"Lutte contre les grossesses pr\u00e9coces\/non d\u00e9sir\u00e9es en milieu scolaire"},"content":{"rendered":"<p><a href=\"http:\/\/pugsada.org\/wordpress\/wp-content\/uploads\/2017\/11\/DSCN0992.jpg\"><img decoding=\"async\" loading=\"lazy\" class=\"size-full wp-image-2086 alignleft\" src=\"http:\/\/pugsada.org\/wordpress\/wp-content\/uploads\/2017\/11\/DSCN0992.jpg\" alt=\"\" width=\"223\" height=\"167\" \/><\/a><a href=\"http:\/\/pugsada.org\/wordpress\/wp-content\/uploads\/2017\/11\/DSCN0999-2.jpg\"><img decoding=\"async\" loading=\"lazy\" class=\"size-full wp-image-2087 alignleft\" src=\"http:\/\/pugsada.org\/wordpress\/wp-content\/uploads\/2017\/11\/DSCN0999-2.jpg\" alt=\"\" width=\"223\" height=\"167\" \/><\/a><\/p>\n<p>Dans le cadre de la lutte contre les grossesses pr\u00e9coces\/non d\u00e9sir\u00e9es en milieu scolaire, l\u2019Association D\u2019appui et d\u2019Eveil Pugsada s\u2019est rendu le 16 novembre 2017 \u00e0 Ziniar\u00e9\u00a0 pour r\u00e9aliser un cin\u00e9-d\u00e9bat sur les m\u00e9faits des grossesses pr\u00e9coces et non d\u00e9sir\u00e9es au profit des \u00e9l\u00e8ves du coll\u00e8ge d\u2019enseignement g\u00e9n\u00e9ral de Nabitenga. Cette activit\u00e9 s\u2019inscrit dans le cadre du <strong>projet de lutte contre les violences faites aux filles et aux femmes par la responsabilisation des hommes dans les localit\u00e9s de Ziniar\u00e9, Zitenga et Nagr\u00e9ongo financ\u00e9 par l\u2019 International <\/strong><strong>Association for\u00a0<\/strong><strong>Maternal and Neo Natal Health<\/strong><strong> (IAMANEH Suisse)<\/strong>.<\/p>\n<p>\u00c0 travers ce projet, l\u2019Association D\u2019appui et d\u2019\u00c9veil Pugsada se propose de contribuer \u00e0 la r\u00e9duction des grossesses pr\u00e9coces et non d\u00e9sir\u00e9es des filles et de les accompagner \u00e0 une vie sociale plus \u00e9panouie d\u2019ici \u00e0 2018.<\/p>\n<p>Lors de ce cin\u00e9-d\u00e9bat, les filles et les gar\u00e7ons ont accord\u00e9 une attention particuli\u00e8re aux messages livr\u00e9s. Les diff\u00e9rentes r\u00e9actions ont donn\u00e9 lieu \u00e0 plusieurs \u00e9changes qui ont permis aux jeunes de comprendre les causes sous-jacentes de la probl\u00e9matique des grossesses en milieu scolaire et les cons\u00e9quences n\u00e9gatives de celles-ci pour leur avenir. Un rappel sur l\u2019importance de l\u2019utilisation des m\u00e9thodes contraceptives a d\u2019ailleurs \u00e9t\u00e9 fait par l\u2019\u00e9quipe d\u2019animation du cin\u00e9-d\u00e9bat.<\/p>\n<p>Cette activit\u00e9 marque la troisi\u00e8me d\u2019une s\u00e9rie de 15 cin\u00e9-d\u00e9bats pr\u00e9vue dans les localit\u00e9s de Ziniar\u00e9, Zitenga, et Nagreongo. Nous vous invitons \u00e0 nous suivre sur notre page Facebook \u00ab<a href=\"http:\/\/facebook.com\/Association-D'appui-et d'Eveil-Pugsada\">\u00a0Association d\u2019Appui et d\u2019\u00c9veil Pugsada<\/a>\u00a0\u00bb pour en savoir davantage sur les activit\u00e9s men\u00e9es par l\u2019Association dans le cadre de ses projets.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Dans le cadre de la lutte contre les grossesses pr\u00e9coces\/non d\u00e9sir\u00e9es en milieu scolaire, l\u2019Association D\u2019appui et d\u2019Eveil Pugsada s\u2019est rendu le 16 novembre 2017 \u00e0 Ziniar\u00e9\u00a0 pour r\u00e9aliser un cin\u00e9-d\u00e9bat sur les m\u00e9faits des grossesses pr\u00e9coces et non d\u00e9sir\u00e9es au profit des \u00e9l\u00e8ves du coll\u00e8ge d\u2019enseignement g\u00e9n\u00e9ral de Nabitenga. Cette activit\u00e9 s\u2019inscrit dans le [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":2087,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":[],"categories":[20],"tags":[],"_links":{"self":[{"href":"https:\/\/pugsada.org\/wordpress\/wp-json\/wp\/v2\/posts\/2083"}],"collection":[{"href":"https:\/\/pugsada.org\/wordpress\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/pugsada.org\/wordpress\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/pugsada.org\/wordpress\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/pugsada.org\/wordpress\/wp-json\/wp\/v2\/comments?post=2083"}],"version-history":[{"count":1,"href":"https:\/\/pugsada.org\/wordpress\/wp-json\/wp\/v2\/posts\/2083\/revisions"}],"predecessor-version":[{"id":2088,"href":"https:\/\/pugsada.org\/wordpress\/wp-json\/wp\/v2\/posts\/2083\/revisions\/2088"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/pugsada.org\/wordpress\/wp-json\/wp\/v2\/media\/2087"}],"wp:attachment":[{"href":"https:\/\/pugsada.org\/wordpress\/wp-json\/wp\/v2\/media?parent=2083"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/pugsada.org\/wordpress\/wp-json\/wp\/v2\/categories?post=2083"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/pugsada.org\/wordpress\/wp-json\/wp\/v2\/tags?post=2083"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}