{"id":2097,"date":"2018-02-08T10:56:46","date_gmt":"2018-02-08T09:56:46","guid":{"rendered":"http:\/\/pugsada.org\/wordpress\/?p=2097"},"modified":"2018-02-08T10:59:56","modified_gmt":"2018-02-08T09:59:56","slug":"seance-danimation-securite-routiere","status":"publish","type":"post","link":"https:\/\/pugsada.org\/wordpress\/seance-danimation-securite-routiere\/","title":{"rendered":"S\u00e9ance d&rsquo;animation sur la s\u00e9curit\u00e9 routi\u00e8re"},"content":{"rendered":"<p>Dans le cadre de ses activit\u00e9s de sensibilisation, l\u2019Association D\u2019appui et d\u2019\u00c9veil Pugsada <a href=\"http:\/\/pugsada.org\/wordpress\/wp-content\/uploads\/2018\/02\/IMAGE-ADEP.jpg\"><img decoding=\"async\" loading=\"lazy\" class=\"wp-image-2098 alignright\" src=\"http:\/\/pugsada.org\/wordpress\/wp-content\/uploads\/2018\/02\/IMAGE-ADEP-180x300.jpg\" alt=\"\" width=\"269\" height=\"449\" srcset=\"https:\/\/pugsada.org\/wordpress\/wp-content\/uploads\/2018\/02\/IMAGE-ADEP-180x300.jpg 180w, https:\/\/pugsada.org\/wordpress\/wp-content\/uploads\/2018\/02\/IMAGE-ADEP-258x430.jpg 258w, https:\/\/pugsada.org\/wordpress\/wp-content\/uploads\/2018\/02\/IMAGE-ADEP.jpg 576w\" sizes=\"(max-width: 269px) 100vw, 269px\" \/><\/a>s\u2019est rendu le jeudi 1<sup>er<\/sup> f\u00e9vrier 2018 au Lyc\u00e9e Marien N\u2019Gouabi pour r\u00e9aliser une animation sur la s\u00e9curit\u00e9 routi\u00e8re au profit des \u00e9l\u00e8ves. Cette activit\u00e9 s\u2019inscrit dans le cadre d\u2019une s\u00e9rie d\u2019animations qui se poursuivra prochainement aux Lyc\u00e9es V\u00e9n\u00e9gr\u00e9 et Du R\u00e9veil \u00e0 travers la mise en \u0153uvre de son projet d\u2019\u00abAutonomisation des jeunes filles des banlieues de Ouagadougou et de Dakar\u00a0: un r\u00e9seau de partenaire mobilis\u00e9s pour une intervention sociale participative\u00a0\u00bb, financ\u00e9 par le Minist\u00e8re des Relations Internationales et de la Francophonie du Qu\u00e9bec avec l\u2019appui technique du Centre de Solidarit\u00e9 International du Canada.<\/p>\n<p>\u00c0 travers l\u2019un des volets du projet, l\u2019Association \u00a0D\u2019appui et d\u2019\u00c9veil Pugsada en collaboration avec l\u2019Office National de la S\u00e9curit\u00e9 Routi\u00e8re (ONASER) se propose de sensibiliser les \u00e9l\u00e8ves et la communaut\u00e9 sur la notion de civisme.<\/p>\n<p>Lors de l\u2019animation, les \u00e9l\u00e8ves ont beaucoup appris sur la s\u00e9curit\u00e9 routi\u00e8re. Plus sp\u00e9cifiquement, ils ont acquis une meilleure connaissance des panneaux de signalisation les plus fr\u00e9quents en circulation ainsi que re\u00e7u des conseils pour une bonne conduite sur la route.<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Dans le cadre de ses activit\u00e9s de sensibilisation, l\u2019Association D\u2019appui et d\u2019\u00c9veil Pugsada s\u2019est rendu le jeudi 1er f\u00e9vrier 2018 au Lyc\u00e9e Marien N\u2019Gouabi pour r\u00e9aliser une animation sur la s\u00e9curit\u00e9 routi\u00e8re au profit des \u00e9l\u00e8ves. Cette activit\u00e9 s\u2019inscrit dans le cadre d\u2019une s\u00e9rie d\u2019animations qui se poursuivra prochainement aux Lyc\u00e9es V\u00e9n\u00e9gr\u00e9 et Du R\u00e9veil [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":[],"categories":[20],"tags":[],"_links":{"self":[{"href":"https:\/\/pugsada.org\/wordpress\/wp-json\/wp\/v2\/posts\/2097"}],"collection":[{"href":"https:\/\/pugsada.org\/wordpress\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/pugsada.org\/wordpress\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/pugsada.org\/wordpress\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/pugsada.org\/wordpress\/wp-json\/wp\/v2\/comments?post=2097"}],"version-history":[{"count":2,"href":"https:\/\/pugsada.org\/wordpress\/wp-json\/wp\/v2\/posts\/2097\/revisions"}],"predecessor-version":[{"id":2100,"href":"https:\/\/pugsada.org\/wordpress\/wp-json\/wp\/v2\/posts\/2097\/revisions\/2100"}],"wp:attachment":[{"href":"https:\/\/pugsada.org\/wordpress\/wp-json\/wp\/v2\/media?parent=2097"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/pugsada.org\/wordpress\/wp-json\/wp\/v2\/categories?post=2097"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/pugsada.org\/wordpress\/wp-json\/wp\/v2\/tags?post=2097"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}