{"id":2436,"date":"2020-02-26T15:15:03","date_gmt":"2020-02-26T14:15:03","guid":{"rendered":"http:\/\/pugsada.org\/wordpress\/?p=2436"},"modified":"2020-02-26T15:15:20","modified_gmt":"2020-02-26T14:15:20","slug":"rencontre-bilan-a-mi-parcours-programme-choix-burkina-faso","status":"publish","type":"post","link":"https:\/\/pugsada.org\/wordpress\/rencontre-bilan-a-mi-parcours-programme-choix-burkina-faso\/","title":{"rendered":"Rencontre bilan \u00e0 mi-parcours du programme son choix au Burkina Faso"},"content":{"rendered":"<p style=\"text-align: left;\"><a href=\"http:\/\/pugsada.org\/wordpress\/wp-content\/uploads\/2020\/02\/image-1.jpg\"><img decoding=\"async\" loading=\"lazy\" class=\"size-medium wp-image-2438 alignleft\" src=\"http:\/\/pugsada.org\/wordpress\/wp-content\/uploads\/2020\/02\/image-1-300x173.jpg\" alt=\"\" width=\"300\" height=\"173\" srcset=\"https:\/\/pugsada.org\/wordpress\/wp-content\/uploads\/2020\/02\/image-1-300x173.jpg 300w, https:\/\/pugsada.org\/wordpress\/wp-content\/uploads\/2020\/02\/image-1-768x443.jpg 768w, https:\/\/pugsada.org\/wordpress\/wp-content\/uploads\/2020\/02\/image-1-746x430.jpg 746w, https:\/\/pugsada.org\/wordpress\/wp-content\/uploads\/2020\/02\/image-1.jpg 1001w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><\/a>Gr\u00e2ce au soutien technique et financier du Minist\u00e8re N\u00e9erlandais des Affaires Etrang\u00e8res et de l\u2019ONG KINDERPOSTZEGELS <strong>s\u2019est tenue les 13 et 14 d\u00e9cembre 2018 un atelier bilan \u00e0 mi parcourt du programme son choix au Burkina Faso<\/strong>.<br \/>\nLa c\u00e9r\u00e9monie d\u2019ouverture \u00e0 \u00e9t\u00e9 ponctu\u00e9e\u00a0 essentiellement par trois discours:<br \/>\nle mot de la Directrice d\u2019ex\u00e9cutive de l\u2019Association d\u2019Appui et d\u2019Eveil Pugsada;<br \/>\nle mot de la Charg\u00e9e des programmes de Kinderpostzegels,<br \/>\nle Discours d\u2019ouverture du Charg\u00e9 d\u2019affaires de l\u2019Ambassade des Pays-Bas aupr\u00e8s du Burkina Faso.<\/p>\n<p>Cet atelier a regroup\u00e9 les acteurs nationaux (le Minist\u00e8re de la sant\u00e9, Minist\u00e8re de la femme, de la solidarit\u00e9 nationale, de la famille et de l\u2019action Humanitaire, minist\u00e8re de l\u2019\u00e9ducation de l\u2019alphab\u00e9tisation et de la promotion des langue nationale, les organisations partenaires de KINDERPOSTZEGELS, CONAMEB ) et internationaux (l\u2019Ambassade des Pays Bas au Burkina, l\u2019ONG Kinderpostzegels, Save the children, UNFPA) qui \u0153uvrent dans la protection des droits des enfants . Au cours de l\u2019atelier, le bilan des actions men\u00e9es au compte du programme son choix et les actions de l\u2019Etat Burkinab\u00e9 en mati\u00e8re de l\u2019\u00e9limination de la pratique du mariage des enfants ont \u00e9t\u00e9 pr\u00e9sent\u00e9s aux participants.<br \/>\n<a href=\"http:\/\/pugsada.org\/wordpress\/wp-content\/uploads\/2020\/02\/image-3.jpg\"><img decoding=\"async\" loading=\"lazy\" class=\"size-medium wp-image-2439 alignleft\" src=\"http:\/\/pugsada.org\/wordpress\/wp-content\/uploads\/2020\/02\/image-3-300x194.jpg\" alt=\"\" width=\"300\" height=\"194\" srcset=\"https:\/\/pugsada.org\/wordpress\/wp-content\/uploads\/2020\/02\/image-3-300x194.jpg 300w, https:\/\/pugsada.org\/wordpress\/wp-content\/uploads\/2020\/02\/image-3-768x496.jpg 768w, https:\/\/pugsada.org\/wordpress\/wp-content\/uploads\/2020\/02\/image-3-666x430.jpg 666w, https:\/\/pugsada.org\/wordpress\/wp-content\/uploads\/2020\/02\/image-3.jpg 978w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><\/a>Il ressort de cet atelier des avanc\u00e9es significatives dans la lutte contre le mariage d\u2019enfants, comme:<br \/>\n&#8211; la prise en compte des mariages religieux et coutumiers pour des besoins de r\u00e9pression en cas de mariage d\u2019enfants dans le code p\u00e9nal adopt\u00e9 en Mai 2018,<br \/>\n&#8211; l\u2019enseignement des th\u00e9matiques du programme dans les \u00e9coles primaires de la zone d\u2019intervention,<br \/>\n&#8211; la prise en compte de la sant\u00e9 sexuelle et reproductive des adolescents dans la politique sanitaire du Burkina,<br \/>\nLes acteurs\u00a0 de lutte contre le mariage d\u2019enfant pr\u00e9sents ont pris\u00a0 l\u2019engagement d\u2019assurer le suivi de la relecture du code des personnes et de la famille.\u00a0\u00a0<a href=\"http:\/\/pugsada.org\/wordpress\/wp-content\/uploads\/2020\/02\/image-4.jpg\"><img decoding=\"async\" loading=\"lazy\" class=\"size-medium wp-image-2440 alignright\" src=\"http:\/\/pugsada.org\/wordpress\/wp-content\/uploads\/2020\/02\/image-4-300x138.jpg\" alt=\"\" width=\"300\" height=\"138\" srcset=\"https:\/\/pugsada.org\/wordpress\/wp-content\/uploads\/2020\/02\/image-4-300x138.jpg 300w, https:\/\/pugsada.org\/wordpress\/wp-content\/uploads\/2020\/02\/image-4-768x353.jpg 768w, https:\/\/pugsada.org\/wordpress\/wp-content\/uploads\/2020\/02\/image-4.jpg 1024w, https:\/\/pugsada.org\/wordpress\/wp-content\/uploads\/2020\/02\/image-4-850x391.jpg 850w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><\/a><br \/>\nIls ont aussi\u00a0 recommand\u00e9 au minist\u00e8re de l\u2019\u00e9ducation, de l\u2019alphab\u00e9tisation et de la promotion des langues nationale (MENAPLN) la g\u00e9n\u00e9ralisation de l\u2019enseignement des th\u00e9matiques en lien\u00a0 avec le mariage d\u2019enfants et autres pratiques n\u00e9fastes.<br \/>\n<a href=\"http:\/\/pugsada.org\/wordpress\/wp-content\/uploads\/2020\/02\/image-2.jpg\"><img decoding=\"async\" loading=\"lazy\" class=\"size-medium wp-image-2441 alignleft\" src=\"http:\/\/pugsada.org\/wordpress\/wp-content\/uploads\/2020\/02\/image-2-300x225.jpg\" alt=\"\" width=\"300\" height=\"225\" srcset=\"https:\/\/pugsada.org\/wordpress\/wp-content\/uploads\/2020\/02\/image-2-300x225.jpg 300w, https:\/\/pugsada.org\/wordpress\/wp-content\/uploads\/2020\/02\/image-2-768x576.jpg 768w, https:\/\/pugsada.org\/wordpress\/wp-content\/uploads\/2020\/02\/image-2-573x430.jpg 573w, https:\/\/pugsada.org\/wordpress\/wp-content\/uploads\/2020\/02\/image-2.jpg 830w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Gr\u00e2ce au soutien technique et financier du Minist\u00e8re N\u00e9erlandais des Affaires Etrang\u00e8res et de l\u2019ONG KINDERPOSTZEGELS s\u2019est tenue les 13 et 14 d\u00e9cembre 2018 un atelier bilan \u00e0 mi parcourt du programme son choix au Burkina Faso. La c\u00e9r\u00e9monie d\u2019ouverture \u00e0 \u00e9t\u00e9 ponctu\u00e9e\u00a0 essentiellement par trois discours: le mot de la Directrice d\u2019ex\u00e9cutive de l\u2019Association [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":2437,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":[],"categories":[20],"tags":[],"_links":{"self":[{"href":"https:\/\/pugsada.org\/wordpress\/wp-json\/wp\/v2\/posts\/2436"}],"collection":[{"href":"https:\/\/pugsada.org\/wordpress\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/pugsada.org\/wordpress\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/pugsada.org\/wordpress\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/pugsada.org\/wordpress\/wp-json\/wp\/v2\/comments?post=2436"}],"version-history":[{"count":2,"href":"https:\/\/pugsada.org\/wordpress\/wp-json\/wp\/v2\/posts\/2436\/revisions"}],"predecessor-version":[{"id":2443,"href":"https:\/\/pugsada.org\/wordpress\/wp-json\/wp\/v2\/posts\/2436\/revisions\/2443"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/pugsada.org\/wordpress\/wp-json\/wp\/v2\/media\/2437"}],"wp:attachment":[{"href":"https:\/\/pugsada.org\/wordpress\/wp-json\/wp\/v2\/media?parent=2436"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/pugsada.org\/wordpress\/wp-json\/wp\/v2\/categories?post=2436"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/pugsada.org\/wordpress\/wp-json\/wp\/v2\/tags?post=2436"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}